{"id":1039,"date":"2019-12-31T12:32:11","date_gmt":"2019-12-31T12:32:11","guid":{"rendered":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/"},"modified":"2019-12-31T12:32:11","modified_gmt":"2019-12-31T12:32:11","slug":"arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce","status":"publish","type":"post","link":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/","title":{"rendered":"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE"},"content":{"rendered":"<p style=\"text-align: justify;\">Seg\u00fan la C\u00e1mara de Comercio de Santiago las ventas a trav\u00e9s del comercio electr\u00f3nico podr\u00edan&nbsp;&nbsp;sobrepasar los US$6500 millones en 2019. Auspicioso se ve el panorama para el canal online chileno, cuya proyecci\u00f3n de crecimiento para el a\u00f1o en curso, seg\u00fan la entidad alcanzar\u00eda el 30% anual. A partir de este crecimiento proyectado, el arriendo de bodegas es una&nbsp;&nbsp;alternativa m\u00e1s eficiente en t\u00e9rminos de costos y flexibilidad para las empresas que implementan el canal Online.<\/p>\n<p style=\"text-align: justify;\">El sostenido crecimiento que ha experimentado el sector e-Commerce en Chile se explica, entre otros factores, por el cambio de paradigma en materia de consumo con la consolidaci\u00f3n de consumidores digitales m\u00e1s empoderados y altamente \u2018tecnologizados\u2019; en el buen desempe\u00f1o general de los canales online desarrollados por los retailers que operan en el pa\u00eds y el desarrollo e impulso de un mercado de PyMes exportadoras\/importadoras con presencia en diversos rubros del comercio.<\/p>\n<p style=\"text-align: justify;\">El aumento en las cifras de movimiento de este canal, sumado a las complejidades de los flujos del comercio electr\u00f3nico y al aumento de los actores ha transformado en un reto para la industria log\u00edstica, cuya tarea hoy en d\u00eda es ofrecer alternativas atractivas que&nbsp;permitan a las compa\u00f1\u00edas crecer, desarrollarse, posicionarse y responder con un servicio de calidad a los exigentes y vertiginosos consumidores digitales\/on line.<\/p>\n<p style=\"text-align: justify;\">En esta l\u00ednea, el mercado de arriendo de superficies para almacenamiento en condominios de bodegas ha experimentado en Chile una importante evoluci\u00f3n, poniendo a disposici\u00f3n nuevos formatos de bodegas y una atractiva gama de servicios complementarios, pensados para contribuir al \u00e9xito del negocio; siempre a un costo muy competitivo y con una flexibilidad que les permite adaptarse a las variaciones en el volumen de operaci\u00f3n, que implica el canal on line.<\/p>\n<p style=\"text-align: justify;\">La flexibilidad que entregan las grandes empresas de almacenamiento ha fortalecido el arriendo frente a la construcci\u00f3n de Centros de Distribuci\u00f3n propios o bajo la modalidad Built to suit, entre los e-Commerce que operan en el pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">En tanto, el buen momento que se pronosticaba para el mercado de centros de bodegaje para este a\u00f1o ya es un hecho, con claros signos de reactivaci\u00f3n en el mercado de bodegaje nacional que se evidenciaron a contar del a\u00f1o pasado. Lo expuesto se sustenta en lo descrito en el Reporte de Mercado de Bodegas realizado por el \u00c1rea de Estudios de Colliers International que expresa que la vacancia de los centros de bodegaje disminuy\u00f3 considerablemente durante el segundo semestre de 2018, pasando de 6,4% a 4,5%, lo que equivale a una superficie disponible de 171.800 m2.<\/p>\n<p><a href=\"http:\/\/bsf.cl\/?utm_source=Logistec&amp;utm_medium=Articulo&amp;utm_campaign=ArticuloPatrocinado&amp;utm_term=ecommerce&amp;utm_content=Articulo-01\" target=\"_blank\" rel=\"noopener\" title=\"Banner BSF 2019\"><img decoding=\"async\" src=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/BSF_Art-01_banner-pat_01.png\" alt=\"BSF Art 01 banner pat 01\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">As\u00ed, a finales del a\u00f1o anterior se vio una alta demanda de empresas buscando alternativas para el escenario de mayor dinamismo que se avecina. En tanto, la mirada de los desarrolladores de Centros Log\u00edsticos est\u00e1 enfocada en sus proyectos futuros, seg\u00fan manifest\u00f3 a Revista Logistec, Diego Castillo Labb\u00e9, Gerente del \u00c1rea Industrial de Colliers International. El experto a\u00f1adi\u00f3 que, \u201cconsiderando el actual crecimiento de la econom\u00eda y sus proyecciones, las empresas ya han experimentado importantes s\u00edntomas de reactivaci\u00f3n que seguir\u00e1n en aumento y beneficiar\u00e1n el desarrollo de este mercado\u201d.<\/p>\n<p style=\"text-align: justify;\">Dentro de este nuevo impulso para la industria, el comercio electr\u00f3nico asoma como uno de los \u00edtems de mayor crecimiento, lo que obliga al sector log\u00edstico a dise\u00f1ar y ofrecer soluciones a la medida de las necesidades de este consolidado canal de venta. En esta l\u00ednea, los actores del mercado de arriendo de Bodegas ofrecen una variada oferta para la operativa del comercio electr\u00f3nico; brindando un servicio de excelencia a trav\u00e9s de procesos y espacios log\u00edsticos m\u00e1s&nbsp;eficientes, donde factores diferenciadores como la flexibilidad, que les permita a las empresas ampliar o reducir las superficies en arriendo de acuerdo a sus requerimientos; la entrega de servicios complementarios que faciliten y apoyen la actividad log\u00edstica de su e-Commerce al interior de los condominios de bodegas; la implementaci\u00f3n de tecnolog\u00edas y sistemas de seguridad perimetral de alto est\u00e1ndar en los centros log\u00edsticos que permitan una operaci\u00f3n segura y fluida; y un servicio al cliente cercano y oportuno para atender en tiempo y forma sus requerimientos inmediatos y futuros, marcan la diferencia en una industria sumamente competitiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">Seg\u00fan la C\u00e1mara de Comercio de Santiago las ventas a trav\u00e9s del comercio electr\u00f3nico podr\u00edan&nbsp;&nbsp;sobrepasar los US$6500 millones en 2019. Auspicioso se ve el panorama para el canal online chileno, cuya proyecci\u00f3n de crecimiento para el a\u00f1o en curso, seg\u00fan la entidad alcanzar\u00eda el 30% anual. A partir de este crecimiento proyectado, el arriendo de bodegas es una&nbsp;&nbsp;alternativa m\u00e1s eficiente en t\u00e9rminos de costos y flexibilidad para las empresas que implementan el canal Online.<\/p>\n","protected":false},"author":1,"featured_media":1036,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[24],"tags":[],"class_list":["post-1039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-almacenamiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE - Revista Logistec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE - Revista Logistec\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan la C\u00e1mara de Comercio de Santiago las ventas a trav\u00e9s del comercio electr\u00f3nico podr\u00edan&nbsp;&nbsp;sobrepasar los US$6500 millones en 2019. Auspicioso se ve el panorama para el canal online chileno, cuya proyecci\u00f3n de crecimiento para el a\u00f1o en curso, seg\u00fan la entidad alcanzar\u00eda el 30% anual. A partir de este crecimiento proyectado, el arriendo de bodegas es una&nbsp;&nbsp;alternativa m\u00e1s eficiente en t\u00e9rminos de costos y flexibilidad para las empresas que implementan el canal Online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Logistec\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-31T12:32:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0\"},\"headline\":\"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE\",\"datePublished\":\"2019-12-31T12:32:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/\"},\"wordCount\":748,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg\",\"articleSection\":[\"ALMACENAMIENTO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/\",\"url\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/\",\"name\":\"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE - Revista Logistec\",\"isPartOf\":{\"@id\":\"https:\/\/www.revistalogistec.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg\",\"datePublished\":\"2019-12-31T12:32:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#primaryimage\",\"url\":\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg\",\"contentUrl\":\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg\",\"width\":850,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.revistalogistec.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.revistalogistec.com\/#website\",\"url\":\"https:\/\/www.revistalogistec.com\/\",\"name\":\"Revista Logistec\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.revistalogistec.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/www.revistalogistec.com\"],\"url\":\"https:\/\/www.revistalogistec.com\/index.php\/author\/admin_revlog\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE - Revista Logistec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/","og_locale":"es_ES","og_type":"article","og_title":"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE - Revista Logistec","og_description":"Seg\u00fan la C\u00e1mara de Comercio de Santiago las ventas a trav\u00e9s del comercio electr\u00f3nico podr\u00edan&nbsp;&nbsp;sobrepasar los US$6500 millones en 2019. Auspicioso se ve el panorama para el canal online chileno, cuya proyecci\u00f3n de crecimiento para el a\u00f1o en curso, seg\u00fan la entidad alcanzar\u00eda el 30% anual. A partir de este crecimiento proyectado, el arriendo de bodegas es una&nbsp;&nbsp;alternativa m\u00e1s eficiente en t\u00e9rminos de costos y flexibilidad para las empresas que implementan el canal Online.","og_url":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/","og_site_name":"Revista Logistec","article_published_time":"2019-12-31T12:32:11+00:00","og_image":[{"width":850,"height":563,"url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#article","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/"},"author":{"name":"admin","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"headline":"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE","datePublished":"2019-12-31T12:32:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/"},"wordCount":748,"commentCount":0,"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg","articleSection":["ALMACENAMIENTO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/","url":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/","name":"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE - Revista Logistec","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#primaryimage"},"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg","datePublished":"2019-12-31T12:32:11+00:00","author":{"@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"breadcrumb":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#primaryimage","url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg","contentUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2019\/12\/ecommerce_bsf_patrocinado.jpg","width":850,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/www.revistalogistec.com\/index.php\/2019\/12\/31\/arriendo-de-bodegas-una-tendencia-en-alza-para-el-sector-e-commerce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.revistalogistec.com\/"},{"@type":"ListItem","position":2,"name":"ARRIENDO DE BODEGAS: UNA TENDENCIA EN ALZA PARA EL SECTOR E-COMMERCE"}]},{"@type":"WebSite","@id":"https:\/\/www.revistalogistec.com\/#website","url":"https:\/\/www.revistalogistec.com\/","name":"Revista Logistec","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistalogistec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.revistalogistec.com"],"url":"https:\/\/www.revistalogistec.com\/index.php\/author\/admin_revlog\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/1039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/comments?post=1039"}],"version-history":[{"count":0,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/1039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media\/1036"}],"wp:attachment":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media?parent=1039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/categories?post=1039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/tags?post=1039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}