{"id":11935,"date":"2023-06-15T13:18:14","date_gmt":"2023-06-15T13:18:14","guid":{"rendered":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/"},"modified":"2023-06-15T13:18:14","modified_gmt":"2023-06-15T13:18:14","slug":"presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios","status":"publish","type":"post","link":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/","title":{"rendered":"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS?"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">1191 d\u00edas en alerta sanitaria por Covid-19. Durante este tiempo, la vida cambi\u00f3 y todos -sin excepci\u00f3n- se adaptaron a las caracter\u00edsticas del mundo pand\u00e9mico. Sin embargo, las cadenas de suministro fueron tremendamente exigidas, obligando a repensar estrategias y a redise\u00f1ar operaciones. \u00bfQu\u00e9 aprendi\u00f3 la log\u00edstica chilena? \u00bfCu\u00e1les son los desaf\u00edos que tiene la industria chilena?&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">No hay dudas de que la gesti\u00f3n eficiente de la cadena de suministro se ha convertido en un factor clave para el \u00e9xito de las empresas en todo el mundo. Sin embargo, el camino hacia esa eficiencia no ha estado exenta de desaf\u00edos y retos importantes que han remecido a la industria, llegando incluso a redefinir las operaciones y su rol.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Los \u00faltimos a\u00f1os no han sido f\u00e1ciles y han estado llenos de cambios significativos en el campo de la log\u00edstica y la cadena de suministros. La pandemia de Covid-19, los avances tecnol\u00f3gicos y las preocupaciones medioambientales han sido factores que han llevado a una reevaluaci\u00f3n profunda de las estrategias y pr\u00e1cticas tradicionales.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Un hito clave que remeci\u00f3 las cadenas de suministros en Chile fue el inicio de las cuarentenas sanitarias anunciadas por las autoridades de salud. A m\u00e1s de tres a\u00f1os de ese momento, la Organizaci\u00f3n Mundial de la Salud puso fin a la alerta sanitaria que reg\u00eda hace 1.191 d\u00edas, por lo que hoy es el momento perfecto para analizar lo aprendido.&nbsp;&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u00bfPero qu\u00e9 aprendimos en estos m\u00e1s de mil d\u00edas de emergencia sanitaria? Hoy queremos entender estos procesos de cambios, comprender el momento que se vive en t\u00e9rminos operacionales y los desaf\u00edos que ha significado para algunas compa\u00f1\u00edas responder a este cambio de ritmo log\u00edstico, obligando a muchos a repensar la forma en que gestionan sus operaciones. \u00bfCu\u00e1l ha sido el alcance de este cambio de estrategia?<\/p>\n<h3 class=\"p1\" style=\"text-align: justify;\">RESILIENCIA Y AGILIDAD: PALABRAS CLAVES<\/h3>\n<p class=\"p1\" style=\"text-align: justify;\">Para muchos estos m\u00e1s de mil d\u00edas fueron un reto, principalmente por la falta de preparaci\u00f3n y flexibilidad de sus operaciones. As\u00ed, el denominado tiempo pand\u00e9mico estuvo marcado por dos conceptos que se transformaron en ejes centrales de las cadenas de suministros: agilidad y resiliencia.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Ambos conceptos reflejan el modo de operar en medio de la incertidumbre, dejando en claro que tanto la resiliencia como la agilidad son fundamentales para una cadena de suministro robusta. Las interrupciones en la producci\u00f3n, las restricciones comerciales y la escasez de suministros han llevado a una mayor atenci\u00f3n en la creaci\u00f3n de cadenas de suministro flexibles y adaptables. Las empresas est\u00e1n diversificando sus proveedores, invirtiendo en tecnolog\u00edas de seguimiento en tiempo real y adoptando enfoques m\u00e1s colaborativos con sus socios comerciales para mitigar los riesgos y responder r\u00e1pidamente a los cambios en la demanda y el entorno.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Otro de los componentes que en tiempos tormentosos tom\u00f3 fuerza fueron las Tecnolog\u00edas Disruptivas, donde la digitalizaci\u00f3n y automatizaci\u00f3n fueron los impulsores de transformaciones y cambios en supply chain. El uso de tecnolog\u00edas como el Internet de las cosas (IoT), la inteligencia artificial (IA) y la anal\u00edtica de datos ha permitido una mayor visibilidad y control en cada etapa de la cadena de suministro. Desde el seguimiento de inventarios en tiempo real hasta la optimizaci\u00f3n de rutas y la gesti\u00f3n predictiva de la demanda, estas herramientas han mejorado la eficiencia operativa y la toma de decisiones informadas.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Los cambios en las cadenas de suministros han sido diversos y uno de estos apunta a la sostenibilidad y responsabilidad social. La sostenibilidad se ha convertido en un factor cr\u00edtico en la gesti\u00f3n de la cadena de suministro. Los consumidores y las regulaciones gubernamentales cada vez m\u00e1s exigentes est\u00e1n impulsando a las empresas a adoptar pr\u00e1cticas m\u00e1s responsables desde el punto de vista ambiental y social. Las empresas est\u00e1n implementando estrategias de cadena de suministro verde, utilizando energ\u00edas renovables, reduciendo el desperdicio y promoviendo condiciones laborales justas. Adem\u00e1s, la transparencia y la trazabilidad se est\u00e1n volviendo esenciales, permitiendo a los consumidores rastrear el origen y las pr\u00e1cticas de producci\u00f3n de los productos que adquieren.<\/p>\n<h3 class=\"p1\" style=\"text-align: justify;\">CHILE Y LOS CAMBIOS&nbsp;<\/h3>\n<p class=\"p1\" style=\"text-align: justify;\">Mil d\u00edas como mil a\u00f1os. As\u00ed de disruptivo han sido los \u00faltimos a\u00f1os. Los cambios que origin\u00f3 el mundo pand\u00e9mico en las cadenas de suministros fueron enormes y dejaron modificaciones que quedaron para siempre y otros que han ido cambiando; sin embargo, hay conceptos que son claves para entender lo que es hoy la nueva log\u00edstica y cu\u00e1les son los desaf\u00edos que a\u00fan quedan por enfrentar.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Para ahondar sobre las ense\u00f1anzas, en esta oportunidad, invitamos a tres consultoras a analizar el momento actual de las operaciones en Chile y lo aprendido, pues mucho de habla en t\u00e9rminos globales, pero considerando las particularidades de la cadena de suministro chilena es importante analizar el momento actual, lo aprendido, los retos y c\u00f3mo seguir potenciando una industria que marca diferencias a nivel pa\u00eds.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">&nbsp;\u00bfCu\u00e1l es el momento de la log\u00edstica chilena? Ante esta pregunta, Daniel Ortega, l\u00edder de supply chain en Deloitte, asegur\u00f3 que el sector ha presentado importantes avances en el \u00faltimo tiempo. \u201cEn t\u00e9rminos de aspectos positivos destaca una infraestructura de transporte bien desarrollada si miramos el resto del continente latinoamericano que incluye aeropuertos, ferrocarriles, una gran extensi\u00f3n de carreteras y puertos mar\u00edtimos, facilitando el movimiento de productos y mejorando la conectividad a lo largo del pa\u00eds\u201d, afirma Ortega.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Para Erika Bustos, manager de Strategy &amp;amp, Operations del \u00e1rea Consultor\u00eda de PWC Chile, la log\u00edstica chilena se ha enfocado en aumentar su productividad para \u201cadaptarse a las nuevas demandas del mercado\u201d y para lograr este objetivo, a juicio de la ejecutiva, ha trabajado en encontrar soluciones que mejoren la eficiencia de los procesos y reduzcan los costos operativos\u201d. En este sentido los cambios en t\u00e9rminos tecnol\u00f3gicos han sido fundamentales.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">El ejecutivo tambi\u00e9n ahond\u00f3 en la resiliencia que se logr\u00f3 durante la pandemia, demostrando la capacidad de adaptarse a las nuevas necesidades, por ejemplo, la implementaci\u00f3n de automatizaci\u00f3n a los CD y la incorporaci\u00f3n de otras tecnolog\u00edas como AGV. AMR, Multi. Shuttles, etc. para ser m\u00e1s eficiente y poder cumplir en tiempo y calidad\u201d.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">En este sentido, Erika valora el aporte de las nuevas tecnolog\u00edas, las cuales \u201chan mejorado la precisi\u00f3n de las operaciones de almacenamiento y preparaci\u00f3n de pedidos. Tambi\u00e9n hay otras tecnolog\u00edas que han permitido un seguimiento m\u00e1s preciso de las etapas y procesos.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">En t\u00e9rminos generales, la ejecutiva de PWC asegura que, en los \u00faltimos a\u00f1os, la log\u00edstica en Chile ha experimentado avances significativos en: infraestructura, tecnolog\u00eda e innovaci\u00f3n. Esto ha permitido un movimiento m\u00e1s eficiente tanto dentro como fuera del pa\u00eds, se ha logrado optimizar las operaciones log\u00edsticas, reduciendo su impacto ambiental y promoviendo la sostenibilidad. Sin embargo, a pesar de estos logros todav\u00eda existen desaf\u00edos que requieren atenci\u00f3n\u201d.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Josue Ojeda, principal CEO de Restructurate coincide en el avance que ha tenido la log\u00edstica nacional en los \u00faltimos a\u00f1os, situaci\u00f3n que -a su juicio- continuar\u00e1, de la mano de \u201cla incorporaci\u00f3n de la tecnolog\u00eda y la digitalizaci\u00f3n que se han convertido en un elemento central del manejo de flujos, procesos e informaci\u00f3n que permite optimizar la cadena\u201d.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">A juicio de Ojeda, los cambios en la log\u00edstica en Chile \u201creflejan la b\u00fasqueda de mayor eficiencia, competitividad y sostenibilidad en la gesti\u00f3n de la cadena de suministro. La digitalizaci\u00f3n, la mejora de la infraestructura, el desarrollo de centros log\u00edsticos y la colaboraci\u00f3n entre los actores claves indican que en la regi\u00f3n\u201d.&nbsp;&nbsp;<\/p>\n<h3 class=\"p1\" style=\"text-align: justify;\">TAREAS PENDIENTES<\/h3>\n<p class=\"p1\" style=\"text-align: justify;\">No obstante, a pesar de lo avanzado, los desaf\u00edos de la log\u00edstica chilena no son pocos. La masificaci\u00f3n de incorporaci\u00f3n de tecnolog\u00edas, la estandarizaci\u00f3n de ciertas etapas log\u00edsticas que agilicen los procesos son algunos de ellos.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><img decoding=\"async\" class=\" alignleft size-full wp-image-11932\" src=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/Daniel_Ortega.jpg\" alt=\"Daniel Ortega\" width=\"200\" style=\"margin: 10px; float: left;\" srcset=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/Daniel_Ortega.jpg 200w, https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/Daniel_Ortega-150x150.jpg 150w, https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/Daniel_Ortega-75x75.jpg 75w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>Por su parte, el l\u00edder de Supply Chain en Deloitte apunta a la presi\u00f3n que existe por la trazabilidad digital y el aumento de la eficiencia dentro de la cadena como algunos de los desaf\u00edos. Tambi\u00e9n, la sostenibilidad y el impacto ambiental, como la reducci\u00f3n de emisiones o la optimizaci\u00f3n de rutas, es -seg\u00fan Ortega- una mirada en la que a\u00fan est\u00e1 al debe el sector log\u00edstico chileno.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Un factor no menor, a juicio de Erika Bustos es el desaf\u00edo de la diversificaci\u00f3n de los modos de transportes, ya que \u201cen gran medida la log\u00edstica en Chile depende en exceso del transporte por carretera. Adem\u00e1s, es necesario mejorar la \u00faltima milla, especialmente, en \u00e1reas remotas o de dif\u00edcil acceso, considerando los desaf\u00edos que implica la geograf\u00eda del pa\u00eds\u201d.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Adicionalmente, la ejecutiva enfatiza en que hoy el sector log\u00edstico se enfrenta a la importante tarea de \u201coptimizar sus procesos, disminuir los tiempos de espera (lead time) y reducir los costos operativos. Esto implica lograr una gesti\u00f3n eficiente de los recursos, permitiendo as\u00ed mantener y operar con eficacia en un entorno log\u00edstico en constante cambio\u201d.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Con una mirada m\u00e1s global y considerando aspectos p\u00fablicos, el Principal CEO de Restructurate reconoce entre los desaf\u00edos de la industria, \u201cla fragmentaci\u00f3n geogr\u00e1fica, las complejidades de los tr\u00e1mites aduaneros, la colaboraci\u00f3n p\u00fablico-privada, las mejoras en infraestructura que aunque se tiene grandes avances no contar con una red ferroviaria que cubra todo el pa\u00eds es una desventaja, entre otros aspectos, sin embargo el desaf\u00edo m\u00e1s importante se encuentra en la capacitaci\u00f3n y formaci\u00f3n de talento\u201d.&nbsp;<\/p>\n<h3 class=\"p1\" style=\"text-align: justify;\">IMPULSO A LA CHILENA<\/h3>\n<p class=\"p1\" style=\"text-align: justify;\">Potenciar la log\u00edstica en Chile es quiz\u00e1s uno de los principales deseos de los actores de la industria y de autoridades estatales. Los beneficios que una cadena de suministro bien aceitada tiene para el desarrollo y la econom\u00eda a nivel pa\u00eds son indiscutibles y por eso, todos est\u00e1n en busca de acciones, mecanismos, procesos y mejoras que permitan potenciar el funcionamiento de la log\u00edstica chilena.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><img decoding=\"async\" class=\" alignright size-full wp-image-11933\" src=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/Erika_Bustos.jpg\" alt=\"Erika Bustos\" width=\"200\" style=\"margin: 10px; float: right;\" srcset=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/Erika_Bustos.jpg 200w, https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/Erika_Bustos-150x150.jpg 150w, https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/Erika_Bustos-75x75.jpg 75w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>En cuanto a las acciones, Bustos destaca algunas que contribuir\u00edan a potenciar la industria, fortaleciendo su competitividad y mejorando la eficiencia: \u201cmejorar y expandir la infraestructura log\u00edstica, incluyendo puertos, carreteras y ferrocarriles con el objetivo de facilitar el movimiento de mercader\u00eda y reducir los tiempos de espera, fomentar la inversi\u00f3n en tecnolog\u00eda, estimular la innovaci\u00f3n y la digitalizaci\u00f3n mediante el apoyo en startups y la implementaci\u00f3n de soluciones disruptivas que optimicen los procesos log\u00edsticos y generen eficiencia y ahorro de costos, promover el desarrollo de proyectos y pol\u00edticas entre el sector p\u00fablico y privado, impulsar la internacionalizaci\u00f3n de la industria log\u00edstica chilena y, por \u00faltimo, invertir en formaci\u00f3n y capacitaci\u00f3n de profesionales en log\u00edstica\u201d.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">A este respecto, Daniel Ortega comenta que las medidas para empujar el desarrollo del sector ser\u00edan: \u201cque las empresas cuenten con una adecuada visualizaci\u00f3n end-to-end de la cadena es clave y para eso existen tecnolog\u00edas que hay que seguir expandiendo en Chile como IOT e Inteligencia Artificial. Tambi\u00e9n es importante potenciar la implementaci\u00f3n de Torres de Control, las cuales mediante el uso de datos hist\u00f3ricos y en tiempo real permiten generar alertas predictivas que ayudan a la toma de decisiones anal\u00edticas y operativas.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Una de las tareas pendientes y que puede marcar diferencias es que las empresas logren un equilibrio entre eficiencia, resiliencia y agilidad. Con esto nos referimos a contar con una operaci\u00f3n log\u00edstica que logre compatibilizar el deseo de reducir costos de inventario, manteniendo altos niveles de servicio, con una que reduzca los riesgos de quiebre de stock y que a la vez permitan innovaciones que proporcionan mayor flexibilidad en la operaci\u00f3n log\u00edstica.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Para Erika, en tanto, es necesario que la industria siga trabajando en la adaptabilidad, \u201cdado que nos encontramos en un entorno en constante cambio\u201d. Adem\u00e1s, llam\u00f3 a estar atentos a las nuevas tecnolog\u00edas que surgen en el mercado y aprovecharlas en beneficio de nuestra industria.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Ambos ejecutivos coinciden en la necesidad de seguir adaptando pr\u00e1cticas m\u00e1s responsables en t\u00e9rminos de Sostenibilidad y Medioambiente. Adem\u00e1s, el sector debe aprender a trabajar de manera colaborativa y cooperativa con todos los actores involucrados en la cadena de suministro, reconociendo que la colaboraci\u00f3n es fundamental para lograr un funcionamiento m\u00e1s eficiente y efectivo.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u201cUna colaboraci\u00f3n m\u00e1s estrecha entre las empresas y sus proveedores permitir\u00eda contar con una mayor transparencia a trav\u00e9s de la cadena de suministro, permitiendo actuar de forma m\u00e1s coordinada. La colaboraci\u00f3n adem\u00e1s brindar\u00eda un intercambio de informaci\u00f3n que permitir\u00eda alinear los intereses de los clientes con la oferta de la empresa\u201d, asegura Daniel Ortega de Deloitte. &nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">En tanto, Josue Ojeda asegura que la industria seguir\u00e1 innovando, porque es factible seguir encontrando oportunidades de mejora en la resiliencia ante las crisis para poder adaptarnos m\u00e1s r\u00e1pido a los imprevistos. Pero el aspecto m\u00e1s relevante es conocer de personas; ya que somos personas comunic\u00e1ndonos, vendiendo, entregando y satisfaciendo a otras personas, por lo que considero que esto es lo m\u00e1s importante para aprender como industria\u201d.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Finalmente, Erika nos define lo que a su juicio ser\u00eda el escenario \u00f3ptimo de la log\u00edstica chilena. \u201cEl escenario \u00f3ptimo ser\u00eda aquel en el que se logra una cadena de suministro altamente eficiente, basada en la innovaci\u00f3n, sostenible y bien conectada\u201d.&nbsp;<\/p>\n<h3 class=\"p1\" style=\"text-align: justify;\">LO APRENDIDO Y EL FUTURO<\/h3>\n<p class=\"p1\" style=\"text-align: justify;\">Si bien no se puede predecir el futuro con certeza, algo se puede vislumbrar, quedando as\u00ed en evidencia lo aprendido y lo que queda por avanzar, apuntando a lo que ser\u00e1n los pr\u00f3ximos cambios en la cadena&nbsp;de suministro.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><img decoding=\"async\" class=\" alignleft size-full wp-image-11934\" src=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/josue_ojeda.jpg\" alt=\"josue ojeda\" width=\"200\" style=\"margin: 10px; float: left;\" srcset=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/josue_ojeda.jpg 200w, https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/josue_ojeda-150x150.jpg 150w, https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/josue_ojeda-75x75.jpg 75w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>Inteligencia Artificial (IA) y Machine Learning (ML): La IA y el ML continuar\u00e1n desempe\u00f1ando un papel crucial en la cadena de suministro. Estas tecnolog\u00edas permiten la automatizaci\u00f3n de tareas repetitivas, la optimizaci\u00f3n de la planificaci\u00f3n y la toma de decisiones basada en datos en tiempo real. Adem\u00e1s, la IA y el ML pueden ayudar en la detecci\u00f3n temprana de problemas, la gesti\u00f3n de riesgos y la identificaci\u00f3n de patrones y oportunidades de mejora.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Blockchain: La tecnolog\u00eda blockchain tiene el potencial de transformar la transparencia y la trazabilidad en la cadena de suministro. Al permitir el registro seguro y descentralizado de transacciones, se puede mejorar la confianza y la autenticidad de la informaci\u00f3n en toda la cadena. Esto es especialmente relevante para la trazabilidad de productos, la gesti\u00f3n de contratos y pagos, as\u00ed como para la prevenci\u00f3n de fraudes y falsificaciones.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Internet de las Cosas (IoT): El IoT seguir\u00e1 creciendo en importancia en la cadena de suministro, con la interconexi\u00f3n de dispositivos y sensores en tiempo real. Esto permitir\u00e1 la monitorizaci\u00f3n continua de las condiciones de almacenamiento y transporte, la gesti\u00f3n eficiente de inventarios y la optimizaci\u00f3n de rutas y tiempos de entrega. Adem\u00e1s, el IoT facilitar\u00e1 la recopilaci\u00f3n de datos valiosos para el an\u00e1lisis y la toma de decisiones basadas en informaci\u00f3n precisa.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Sostenibilidad y econom\u00eda circular: La sostenibilidad seguir\u00e1 siendo una preocupaci\u00f3n central en la cadena de suministro. Las empresas se esforzaron por reducir su huella ambiental, adoptando pr\u00e1cticas de fabricaci\u00f3n y log\u00edstica m\u00e1s sostenibles, as\u00ed como enfoc\u00e1ndose en la econom\u00eda circular y el reciclaje. Adem\u00e1s, es probable que los consumidores demanden cada vez m\u00e1s productos eco-friendly y transparentes en t\u00e9rminos de impacto ambiental.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Personalizaci\u00f3n y experiencia del cliente: Con la creciente demanda de productos personalizados y la competencia en la experiencia del cliente, las empresas deber\u00e1n adaptar sus cadenas de suministro para cumplir con estas expectativas. La capacidad de ofrecer productos y servicios personalizados en tiempos de entrega r\u00e1pidos se convertir\u00e1 en un diferenciador clave en el mercado. La tecnolog\u00eda desempe\u00f1ar\u00e1 un papel fundamental en la agilidad y la flexibilidad necesarias para lograr esta personalizaci\u00f3n.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Estas son solo algunas de las tendencias que podr\u00edan influir en los pr\u00f3ximos cambios en la cadena de suministro. A medida que avanza la tecnolog\u00eda y surgen nuevas necesidades y desaf\u00edos, la adaptabilidad y la innovaci\u00f3n seguir\u00e1n siendo fundamentales para mantener una cadena de suministro competitiva y eficiente.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">1191 d\u00edas en alerta sanitaria por Covid-19. Durante este tiempo, la vida cambi\u00f3 y todos -sin excepci\u00f3n- se adaptaron a las caracter\u00edsticas del mundo pand\u00e9mico. Sin embargo, las cadenas de suministro fueron tremendamente exigidas, obligando a repensar estrategias y a redise\u00f1ar operaciones. \u00bfQu\u00e9 aprendi\u00f3 la log\u00edstica chilena? \u00bfCu\u00e1les son los desaf\u00edos que tiene la industria chilena?&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":11929,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[79],"tags":[],"class_list":["post-11935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-punto-de-vista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS? - Revista Logistec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS? - Revista Logistec\" \/>\n<meta property=\"og:description\" content=\"1191 d\u00edas en alerta sanitaria por Covid-19. Durante este tiempo, la vida cambi\u00f3 y todos -sin excepci\u00f3n- se adaptaron a las caracter\u00edsticas del mundo pand\u00e9mico. Sin embargo, las cadenas de suministro fueron tremendamente exigidas, obligando a repensar estrategias y a redise\u00f1ar operaciones. \u00bfQu\u00e9 aprendi\u00f3 la log\u00edstica chilena? \u00bfCu\u00e1les son los desaf\u00edos que tiene la industria chilena?&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Logistec\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-15T13:18:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/pvista_ed136.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\"},\"headline\":\"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS?\",\"datePublished\":\"2023-06-15T13:18:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/\"},\"wordCount\":2860,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/pvista_ed136.jpg\",\"articleSection\":[\"PUNTO DE VISTA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/\",\"name\":\"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS? - Revista Logistec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/pvista_ed136.jpg\",\"datePublished\":\"2023-06-15T13:18:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/pvista_ed136.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/pvista_ed136.jpg\",\"width\":850,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2023\\\/06\\\/15\\\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.revistalogistec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#website\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/\",\"name\":\"Revista Logistec\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revistalogistec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.revistalogistec.com\"],\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/author\\\/admin_revlog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS? - Revista Logistec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/","og_locale":"es_ES","og_type":"article","og_title":"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS? - Revista Logistec","og_description":"1191 d\u00edas en alerta sanitaria por Covid-19. Durante este tiempo, la vida cambi\u00f3 y todos -sin excepci\u00f3n- se adaptaron a las caracter\u00edsticas del mundo pand\u00e9mico. Sin embargo, las cadenas de suministro fueron tremendamente exigidas, obligando a repensar estrategias y a redise\u00f1ar operaciones. \u00bfQu\u00e9 aprendi\u00f3 la log\u00edstica chilena? \u00bfCu\u00e1les son los desaf\u00edos que tiene la industria chilena?&nbsp;","og_url":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/","og_site_name":"Revista Logistec","article_published_time":"2023-06-15T13:18:14+00:00","og_image":[{"width":850,"height":530,"url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/pvista_ed136.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/#article","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/"},"author":{"name":"admin","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"headline":"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS?","datePublished":"2023-06-15T13:18:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/"},"wordCount":2860,"commentCount":0,"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/pvista_ed136.jpg","articleSection":["PUNTO DE VISTA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/","url":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/","name":"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS? - Revista Logistec","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/#primaryimage"},"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/pvista_ed136.jpg","datePublished":"2023-06-15T13:18:14+00:00","author":{"@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"breadcrumb":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/#primaryimage","url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/pvista_ed136.jpg","contentUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2023\/06\/pvista_ed136.jpg","width":850,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/www.revistalogistec.com\/index.php\/2023\/06\/15\/presente-y-futuro-de-la-logistica-chilena-como-la-pandemia-redefinio-la-operacion-y-planteo-nuevos-desafios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.revistalogistec.com\/"},{"@type":"ListItem","position":2,"name":"PRESENTE Y FUTURO DE LA LOG\u00cdSTICA CHILENA: \u00bfC\u00d3MO LA PANDEMIA REDEFINI\u00d3 LA OPERACI\u00d3N Y PLANTE\u00d3 NUEVOS DESAF\u00cdOS?"}]},{"@type":"WebSite","@id":"https:\/\/www.revistalogistec.com\/#website","url":"https:\/\/www.revistalogistec.com\/","name":"Revista Logistec","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistalogistec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.revistalogistec.com"],"url":"https:\/\/www.revistalogistec.com\/index.php\/author\/admin_revlog\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/11935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/comments?post=11935"}],"version-history":[{"count":0,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/11935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media\/11929"}],"wp:attachment":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media?parent=11935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/categories?post=11935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/tags?post=11935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}