{"id":15493,"date":"2024-06-26T13:51:21","date_gmt":"2024-06-26T13:51:21","guid":{"rendered":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/"},"modified":"2024-06-26T13:51:21","modified_gmt":"2024-06-26T13:51:21","slug":"la-sustentabilidad-como-modelo-de-desarrollo-pep","status":"publish","type":"post","link":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/","title":{"rendered":"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+"},"content":{"rendered":"<p style=\"text-align: justify;\">PepsiCo M\u00e9xico public\u00f3 su Reporte ESG 2023, sobre sus avances respecto a los criterios ambientales, sociales y de gobernanza que gu\u00edan su transformaci\u00f3n estrat\u00e9gica pep+.&nbsp;M\u00e1s de 260 productores de pl\u00e1tano verde de Tabasco se incorporaron a la cadena de valor de la compa\u00f1\u00eda para la producci\u00f3n de Natuchips, por medio del programa Agrovita.&nbsp;La compa\u00f1\u00eda logr\u00f3 una reducci\u00f3n de 30&nbsp;% en el uso de agua para los campos de papa de Sabritas.<\/p>\n<p style=\"text-align: justify;\">Como parte de su agenda a escala global y de su estrategia pep+, PepsiCo M\u00e9xico present\u00f3 sus avances en materia de gobernanza social, ambiental y corporativa por medio de su Reporte ESG 2023.<\/p>\n<p style=\"text-align: justify;\">PepsiCo Positivo (pep+) representa la transformaci\u00f3n estrat\u00e9gica de la compa\u00f1\u00eda, que pone en el centro a las personas y la sustentabilidad para crear valor e inspirar a otros a tomar mejores decisiones para s\u00ed mismas y para el planeta.<\/p>\n<p style=\"text-align: justify;\">En M\u00e9xico destaca Agrovita, un programa que apoya a peque\u00f1os productores de cacao, pl\u00e1tano y palma en los estados de Tabasco, Chiapas y Campeche. Mediante capacitaciones para la adopci\u00f3n de pr\u00e1cticas agr\u00edcolas regenerativas y con educaci\u00f3n financiera, as\u00ed como con la instalaci\u00f3n de parcelas demostrativas, huertos comunitarios, sistemas de captaci\u00f3n de agua pluvial y tanques comunitarios, PepsiCo M\u00e9xico benefici\u00f3 a 13&nbsp;741 personas (37&nbsp;% de las cuales son mujeres) e intervino 4&nbsp;488 hect\u00e1reas con pr\u00e1cticas de agricultura regenerativa.<\/p>\n<h3 style=\"text-align: justify;\">Otros avances que la empresa dio a conocer incluyen:<\/h3>\n<p style=\"text-align: justify;\">\u2022 La incorporaci\u00f3n de m\u00e1s de 260 nuevos peque\u00f1os productores de pl\u00e1tano a la cadena de valor, quienes han vendido m\u00e1s de 232 toneladas de pl\u00e1tano verde a la empresa para la producci\u00f3n de Natuchips, una botana que se lanz\u00f3 en 2024. <\/p>\n<p style=\"text-align: justify;\">\u2022 Gracias a la alianza con Grupo Trimex y el Centro Internacional de Mejoramiento de Ma\u00edz y Trigo (CIMMYT), PepsiCo dio apoyo \u2014por tercer a\u00f1o consecutivo\u2014 a productores de trigo en la zona del Baj\u00edo. Al desarrollar nuevas capacidades entre los agricultores y otros actores clave del ciclo agr\u00edcola, la empresa ha facilitado la adopci\u00f3n de innovaciones tecnol\u00f3gicas que han hecho posible cultivos cada vez m\u00e1s sustentables.<\/p>\n<p style=\"text-align: justify;\">\u2022 PepsiCo ha reducido en 30&nbsp;% el uso de agua en sus campos de cultivo de papa, lo cual representa un ahorro de 14 mil millones de metros c\u00fabicos de agua, equivalentes a m\u00e1s de cuatro mil albercas ol\u00edmpicas. Esto fue posible gracias a la conversi\u00f3n a sistemas de alta eficiencia, como el goteo, y a la introducci\u00f3n de sistemas de inteligencia artificial, estaciones meteorol\u00f3gicas y riego digital.<\/p>\n<p style=\"text-align: justify;\">\u2022 Un aumento de 26&nbsp;% de jardines florales en campos de cultivo de papa para la conservaci\u00f3n de las abejas. Con la instalaci\u00f3n de colmenas, PepsiCo M\u00e9xico contribuye a la conservaci\u00f3n de una poblaci\u00f3n estimada de 1.9 millones de abejas.<\/p>\n<p style=\"text-align: justify;\">\u2022 Agricultores de Sinaloa, proveedores de la compa\u00f1\u00eda, obtuvieron la certificaci\u00f3n de sustentabilidad para el cultivo de ma\u00edz en M\u00e9xico. Esto representa 20 % de la producci\u00f3n total de ma\u00edz destinada al portafolio de alimentos de PepsiCo M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">Con el pilar Cadena de Valor Positiva, PepsiCo tiene el objetivo global de ser una empresa con emisiones netas cero para 2040 y convertirse en una empresa Net Water Positive para 2030, es decir, restablecer m\u00e1s agua de la que consume en zonas con alto estr\u00e9s h\u00eddrico. Algunos de los avances en M\u00e9xico en 2023 contemplan:<\/p>\n<p style=\"text-align: justify;\">\u2022 La reducci\u00f3n de m\u00e1s de 30&nbsp;% de emisiones de CO2 en plantas de manufactura gracias a la implementaci\u00f3n de distintas tecnolog\u00edas sustentables.<\/p>\n<p style=\"text-align: justify;\">\u2022 La incorporaci\u00f3n de 320 nuevas unidades de reparto el\u00e9ctricas y un tractocami\u00f3n el\u00e9ctrico, con lo que se redujo la emisi\u00f3n de 2&nbsp;845 toneladas de CO2 al a\u00f1o.<\/p>\n<p style=\"text-align: justify;\">\u2022 PepsiCo M\u00e9xico cumpli\u00f3 cinco a\u00f1os como una empresa Zero Waste to Landfill, es decir, una compa\u00f1\u00eda sin residuos en sus operaciones de manufactura que lleguen a los rellenos sanitarios.<\/p>\n<p style=\"text-align: justify;\">\u2022 Gracias a su estrategia de sustentabilidad de envases y empaques, en 2023 se logr\u00f3 recolectar 75&nbsp;% de los empaques flexibles.<\/p>\n<p style=\"text-align: justify;\">\u2022 Por medio de la implementaci\u00f3n de distintas tecnolog\u00edas, la empresa logr\u00f3 una reducci\u00f3n de 70&nbsp;% en el consumo de agua en sus plantas desde 2015. PepsiCo M\u00e9xico ahorra 20 millones de litros de agua al a\u00f1o en sus plantas de manufactura.<\/p>\n<p style=\"text-align: justify;\">El pilar Elecciones Positivas busca inspirar a las personas para que tomen las mejores decisiones para ellas y el planeta. Con este pilar, la empresa present\u00f3 los siguientes avances:<\/p>\n<p style=\"text-align: justify;\">\u2022 Promoci\u00f3n del deporte en Iztapalapa, Ciudad de M\u00e9xico. Como parte de la iniciativa global Sabritas Replay, la marca inaugur\u00f3, a finales de 2022, una cancha de futbol construida con empaques reciclados. A lo largo de 2023, en colaboraci\u00f3n con la Fundaci\u00f3n Futbol M\u00e1s, se implementaron 382 actividades sociodeportivas, lo cual benefici\u00f3 a 359 ni\u00f1os, ni\u00f1as y j\u00f3venes.<\/p>\n<p style=\"text-align: justify;\">\u2022 La iniciativa Gatorade Equity in Sports busca que toda persona tenga las mismas oportunidades de practicar deporte y desarrollar su potencial. En 2023 se ampli\u00f3 el apoyo a los atletas por medio de alianzas y donaciones locales. A la fecha, Gatorade ha contribuido con siete millones de d\u00f3lares en donaciones y ha apoyado a dos mil organizaciones sin \u00e1nimo de lucro, lo cual ha beneficiado a 400 mil atletas en el mundo.<\/p>\n<p style=\"text-align: justify;\">PepsiCo contin\u00faa transformando su manera de hacer negocios para encaminarse a lograr un planeta m\u00e1s sano y sistemas alimentarios m\u00e1s resilientes, as\u00ed como contribuir al bienestar integral de la gente y las comunidades a las que sirve.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">PepsiCo M\u00e9xico public\u00f3 su Reporte ESG 2023, sobre sus avances respecto a los criterios ambientales, sociales y de gobernanza que gu\u00edan su transformaci\u00f3n estrat\u00e9gica pep+.&nbsp;M\u00e1s de 260 productores de pl\u00e1tano verde de Tabasco se incorporaron a la cadena de valor de la compa\u00f1\u00eda para la producci\u00f3n de Natuchips, por medio del programa Agrovita.&nbsp;La compa\u00f1\u00eda logr\u00f3 una reducci\u00f3n de 30&nbsp;% en el uso de agua para los campos de papa de Sabritas.<\/p>\n","protected":false},"author":1,"featured_media":15491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[12],"tags":[],"class_list":["post-15493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+ - Revista Logistec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+ - Revista Logistec\" \/>\n<meta property=\"og:description\" content=\"PepsiCo M\u00e9xico public\u00f3 su Reporte ESG 2023, sobre sus avances respecto a los criterios ambientales, sociales y de gobernanza que gu\u00edan su transformaci\u00f3n estrat\u00e9gica pep+.&nbsp;M\u00e1s de 260 productores de pl\u00e1tano verde de Tabasco se incorporaron a la cadena de valor de la compa\u00f1\u00eda para la producci\u00f3n de Natuchips, por medio del programa Agrovita.&nbsp;La compa\u00f1\u00eda logr\u00f3 una reducci\u00f3n de 30&nbsp;% en el uso de agua para los campos de papa de Sabritas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Logistec\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-26T13:51:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2024\/06\/flota-electrica-03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\"},\"headline\":\"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+\",\"datePublished\":\"2024-06-26T13:51:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/\"},\"wordCount\":949,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/flota-electrica-03.jpg\",\"articleSection\":[\"NOTICIAS INDUSTRIA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/\",\"name\":\"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+ - Revista Logistec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/flota-electrica-03.jpg\",\"datePublished\":\"2024-06-26T13:51:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/flota-electrica-03.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/flota-electrica-03.jpg\",\"width\":850,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2024\\\/06\\\/26\\\/la-sustentabilidad-como-modelo-de-desarrollo-pep\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.revistalogistec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#website\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/\",\"name\":\"Revista Logistec\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revistalogistec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.revistalogistec.com\"],\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/author\\\/admin_revlog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+ - Revista Logistec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/","og_locale":"es_ES","og_type":"article","og_title":"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+ - Revista Logistec","og_description":"PepsiCo M\u00e9xico public\u00f3 su Reporte ESG 2023, sobre sus avances respecto a los criterios ambientales, sociales y de gobernanza que gu\u00edan su transformaci\u00f3n estrat\u00e9gica pep+.&nbsp;M\u00e1s de 260 productores de pl\u00e1tano verde de Tabasco se incorporaron a la cadena de valor de la compa\u00f1\u00eda para la producci\u00f3n de Natuchips, por medio del programa Agrovita.&nbsp;La compa\u00f1\u00eda logr\u00f3 una reducci\u00f3n de 30&nbsp;% en el uso de agua para los campos de papa de Sabritas.","og_url":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/","og_site_name":"Revista Logistec","article_published_time":"2024-06-26T13:51:21+00:00","og_image":[{"width":850,"height":530,"url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2024\/06\/flota-electrica-03.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/#article","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/"},"author":{"name":"admin","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"headline":"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+","datePublished":"2024-06-26T13:51:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/"},"wordCount":949,"commentCount":0,"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2024\/06\/flota-electrica-03.jpg","articleSection":["NOTICIAS INDUSTRIA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/","url":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/","name":"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+ - Revista Logistec","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/#primaryimage"},"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2024\/06\/flota-electrica-03.jpg","datePublished":"2024-06-26T13:51:21+00:00","author":{"@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"breadcrumb":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/#primaryimage","url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2024\/06\/flota-electrica-03.jpg","contentUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2024\/06\/flota-electrica-03.jpg","width":850,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/www.revistalogistec.com\/index.php\/2024\/06\/26\/la-sustentabilidad-como-modelo-de-desarrollo-pep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.revistalogistec.com\/"},{"@type":"ListItem","position":2,"name":"LA SUSTENTABILIDAD COMO MODELO DE DESARROLLO: PEP+"}]},{"@type":"WebSite","@id":"https:\/\/www.revistalogistec.com\/#website","url":"https:\/\/www.revistalogistec.com\/","name":"Revista Logistec","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistalogistec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.revistalogistec.com"],"url":"https:\/\/www.revistalogistec.com\/index.php\/author\/admin_revlog\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/15493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/comments?post=15493"}],"version-history":[{"count":0,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/15493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media\/15491"}],"wp:attachment":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media?parent=15493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/categories?post=15493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/tags?post=15493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}