{"id":17780,"date":"2025-09-16T13:55:27","date_gmt":"2025-09-16T13:55:27","guid":{"rendered":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/"},"modified":"2025-09-16T13:55:27","modified_gmt":"2025-09-16T13:55:27","slug":"como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla","status":"publish","type":"post","link":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/","title":{"rendered":"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA"},"content":{"rendered":"<p style=\"text-align: justify;\">La Inteligencia Artificial ha traspasado de la ficci\u00f3n a la realidad con una velocidad abismante. &nbsp;Todas las esferas del quehacer humano han sido permeadas por estas herramientas que parecen razonar y trabajar con una inmediatez impensada para el mundo real. Entre ellas, se incluye, por supuesto el sector log\u00edstico, donde su uso se ha convertido en un pilar fundamental. Hoy ya no se trata solo de automatizar procesos, sino de reinventar por completo la forma en que las empresas planifican, ejecutan y supervisan sus operaciones. Tanto es as\u00ed que actualmente se puede decir con propiedad que se ha abierto la puerta a un nuevo modelo log\u00edstico: m\u00e1s veloz, m\u00e1s preciso y, sobre todo, m\u00e1s rentable.<\/p>\n<p style=\"text-align: justify;\">Aunque sectores como la salud, el retail y las finanzas han mostrado de manera evidente el poder de la IA, es en la log\u00edstica de \u00faltima milla donde se ha producido una verdadera revoluci\u00f3n. Este tramo de la cadena de suministro \u2014que se carectertiza por ser el m\u00e1s costoso y complejo\u2014, ha sido transformado gracias a algoritmos y modelos de Machine Learning, capaces de optimizar rutas en cuesti\u00f3n de segundos, adaptarse a las condiciones del tr\u00e1fico o el clima en tiempo real y reducir tanto el consumo de combustible como los kil\u00f3metros recorridos.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan <a href=\"https:\/\/www.mckinsey.com\/industries\/metals-and-mining\/our-insights\/succeeding-in-the-ai-supply-chain-revolution?utm_source=chatgpt.com\">datos<\/a> de McKensey &amp; Company, la implementaci\u00f3n exitosa de la gesti\u00f3n de la cadena de suministro basada en IA ha permitido a los primeros usuarios reducir los costos log\u00edsticos en un 15% y los niveles de inventario en un 35%, en relaci\u00f3n con competidores que no han adoptado esta tecnolog\u00eda o que lo han hecho solo parcialmente. Estas cifras se dan en parte por la precisi\u00f3n que la IA es capaz de ofrecer, lo que a su vez permite realizar procesos m\u00e1s sostenibles.<\/p>\n<p style=\"text-align: justify;\">El efecto en el consumidor final adem\u00e1s ha sido innegable. En un mundo donde el comercio electr\u00f3nico domina y las expectativas son cada vez m\u00e1s altas, los clientes demandan entregas r\u00e1pidas, seguras y predecibles, tres exigencias en para esta tecnolog\u00eda son grandes fortalezas . La IA ha hecho posible que las empresas ofrezcan tiempos estimados de llegada con un nivel de precisi\u00f3n superior al 98%, lo que ha permitido ir erradicando ventanas de entrega demasiado amplias y ofrecer transparencia total sobre el estado de cada pedido.<\/p>\n<p style=\"text-align: justify;\">La IA tambi\u00e9n permite personalizar las opciones de entrega seg\u00fan los h\u00e1bitos de compra, anticipar retrasos con alertas proactivas y mantener informado al consumidor en tiempo real mediante notificaciones por correo, mensajes instant\u00e1neos o aplicaciones m\u00f3viles. De esta manera, las compa\u00f1\u00edas que integran IA en sus operaciones no solo cumplen con lo que el cliente espera, sino que logran superar sus ya altas expectativas.<\/p>\n<p style=\"text-align: justify;\">Detr\u00e1s de esta transformaci\u00f3n se encuentra el poder del Machine Learning, que convierte grandes vol\u00famenes de datos en acciones estrat\u00e9gicas concretas. En el mundo log\u00edstico, esto permite prever la demanda y ajustar los inventarios, asignar pedidos al repartidor m\u00e1s eficiente, identificar patrones que reduzcan errores en la operaci\u00f3n y mejorar continuamente las rutas. En cada entrega se genera aprendizaje, y ese aprendizaje se traduce en mayor velocidad, menores costos y operaciones m\u00e1s rentables.<\/p>\n<p style=\"text-align: justify;\">La revoluci\u00f3n apenas comienza. Los pr\u00f3ximos a\u00f1os traer\u00e1n consigo chatbots capaces de gestionar pedidos y reprogramar entregas en segundos, camiones aut\u00f3nomos que recorrer\u00e1n tanto las ciudades como tramos interurbanos y sistemas de inventario que se autoabastecen con base en la demanda real. Se trata de una tendencia irreversible. Las reglas del juego en la log\u00edstica ya cambiaron y quienes se preparen hoy estar\u00e1n en posici\u00f3n de liderar ma\u00f1ana, tanto en Am\u00e9rica Latina como en el resto del mundo. Quienes no lo hagan, corren el riesgo de quedarse fuera de un mercado cada vez m\u00e1s competitivo.<\/p>\n<p style=\"text-align: justify;\">Por Carlos D\u00edaz Ojeda, General Manager de DispatchTrack Latinoam\u00e9rica<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">La Inteligencia Artificial ha traspasado de la ficci\u00f3n a la realidad con una velocidad abismante. &nbsp;Todas las esferas del quehacer humano han sido permeadas por estas herramientas que parecen razonar y trabajar con una inmediatez impensada para el mundo real. Entre ellas, se incluye, por supuesto el sector log\u00edstico, donde su uso se ha convertido en un pilar fundamental. Hoy ya no se trata solo de automatizar procesos, sino de reinventar por completo la forma en que las empresas planifican, ejecutan y supervisan sus operaciones. Tanto es as\u00ed que actualmente se puede decir con propiedad que se ha abierto la puerta a un nuevo modelo log\u00edstico: m\u00e1s veloz, m\u00e1s preciso y, sobre todo, m\u00e1s rentable.<\/p>\n","protected":false},"author":1,"featured_media":17779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[12],"tags":[],"class_list":["post-17780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-industria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA - Revista Logistec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA - Revista Logistec\" \/>\n<meta property=\"og:description\" content=\"La Inteligencia Artificial ha traspasado de la ficci\u00f3n a la realidad con una velocidad abismante. &nbsp;Todas las esferas del quehacer humano han sido permeadas por estas herramientas que parecen razonar y trabajar con una inmediatez impensada para el mundo real. Entre ellas, se incluye, por supuesto el sector log\u00edstico, donde su uso se ha convertido en un pilar fundamental. Hoy ya no se trata solo de automatizar procesos, sino de reinventar por completo la forma en que las empresas planifican, ejecutan y supervisan sus operaciones. Tanto es as\u00ed que actualmente se puede decir con propiedad que se ha abierto la puerta a un nuevo modelo log\u00edstico: m\u00e1s veloz, m\u00e1s preciso y, sobre todo, m\u00e1s rentable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Logistec\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T13:55:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2025\/09\/dt-latam-stock-carlos-diaz-2-1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\"},\"headline\":\"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA\",\"datePublished\":\"2025-09-16T13:55:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/\"},\"wordCount\":683,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/dt-latam-stock-carlos-diaz-2-1-3.jpg\",\"articleSection\":[\"NOTICIAS INDUSTRIA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/\",\"name\":\"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA - Revista Logistec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/dt-latam-stock-carlos-diaz-2-1-3.jpg\",\"datePublished\":\"2025-09-16T13:55:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/dt-latam-stock-carlos-diaz-2-1-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/dt-latam-stock-carlos-diaz-2-1-3.jpg\",\"width\":850,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2025\\\/09\\\/16\\\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.revistalogistec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#website\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/\",\"name\":\"Revista Logistec\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revistalogistec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.revistalogistec.com\"],\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/author\\\/admin_revlog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA - Revista Logistec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA - Revista Logistec","og_description":"La Inteligencia Artificial ha traspasado de la ficci\u00f3n a la realidad con una velocidad abismante. &nbsp;Todas las esferas del quehacer humano han sido permeadas por estas herramientas que parecen razonar y trabajar con una inmediatez impensada para el mundo real. Entre ellas, se incluye, por supuesto el sector log\u00edstico, donde su uso se ha convertido en un pilar fundamental. Hoy ya no se trata solo de automatizar procesos, sino de reinventar por completo la forma en que las empresas planifican, ejecutan y supervisan sus operaciones. Tanto es as\u00ed que actualmente se puede decir con propiedad que se ha abierto la puerta a un nuevo modelo log\u00edstico: m\u00e1s veloz, m\u00e1s preciso y, sobre todo, m\u00e1s rentable.","og_url":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/","og_site_name":"Revista Logistec","article_published_time":"2025-09-16T13:55:27+00:00","og_image":[{"width":850,"height":530,"url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2025\/09\/dt-latam-stock-carlos-diaz-2-1-3.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/#article","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/"},"author":{"name":"admin","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"headline":"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA","datePublished":"2025-09-16T13:55:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/"},"wordCount":683,"commentCount":0,"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2025\/09\/dt-latam-stock-carlos-diaz-2-1-3.jpg","articleSection":["NOTICIAS INDUSTRIA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/","url":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/","name":"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA - Revista Logistec","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/#primaryimage"},"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2025\/09\/dt-latam-stock-carlos-diaz-2-1-3.jpg","datePublished":"2025-09-16T13:55:27+00:00","author":{"@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"breadcrumb":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/#primaryimage","url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2025\/09\/dt-latam-stock-carlos-diaz-2-1-3.jpg","contentUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2025\/09\/dt-latam-stock-carlos-diaz-2-1-3.jpg","width":850,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/www.revistalogistec.com\/index.php\/2025\/09\/16\/como-la-ia-cambia-las-reglas-del-juego-en-la-ultima-milla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.revistalogistec.com\/"},{"@type":"ListItem","position":2,"name":"C\u00d3MO LA IA CAMBIA LAS REGLAS DEL JUEGO EN LA \u00daLTIMA MILLA"}]},{"@type":"WebSite","@id":"https:\/\/www.revistalogistec.com\/#website","url":"https:\/\/www.revistalogistec.com\/","name":"Revista Logistec","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistalogistec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.revistalogistec.com"],"url":"https:\/\/www.revistalogistec.com\/index.php\/author\/admin_revlog\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/17780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/comments?post=17780"}],"version-history":[{"count":0,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/17780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media\/17779"}],"wp:attachment":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media?parent=17780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/categories?post=17780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/tags?post=17780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}