{"id":7078,"date":"2021-11-12T11:59:55","date_gmt":"2021-11-12T11:59:55","guid":{"rendered":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/"},"modified":"2021-11-12T11:59:55","modified_gmt":"2021-11-12T11:59:55","slug":"tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022","status":"publish","type":"post","link":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/","title":{"rendered":"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022"},"content":{"rendered":"<p style=\"text-align: justify;\">Simplemente no se sabe qu\u00e9 traer\u00e1 el nuevo a\u00f1o en t\u00e9rminos de desaf\u00edos log\u00edsticos emergentes. Despu\u00e9s de dos a\u00f1os incre\u00edblemente desafiantes en la industria de la log\u00edstica global, dejemos de lado cualquier expectativa de que el panorama, alguna vez, vuelva a la \u00abnormalidad\u00bb.<\/p>\n<p style=\"text-align: justify;\">Las interrupciones contin\u00faan afectando nuestra vida cotidiana: la escasez de materias primas y componentes, poca mano de obra, el cierre de puertos, el aumento de los costos del combustible, el alza de los costos de las mercanc\u00edas y otras fuerzas continuar\u00e1n ejerciendo enormes presiones sobre las cadenas de suministro mundiales en 2022. Incertidumbre extrema tanto en la demanda y la oferta continuar\u00e1n en el futuro previsible para muchas industrias.<\/p>\n<p style=\"text-align: justify;\">Una vez m\u00e1s, corresponder\u00e1 a los equipos de log\u00edstica brindar un servicio mejor y m\u00e1s r\u00e1pido, a un costo menor. Y bajo este escenario, hay 3 imperativos para los equipos de log\u00edstica, basados \u200b\u200ben nuestra experiencia compartida en este tiempo:<\/p>\n<p style=\"text-align: justify;\">\u2022 Los equipos de log\u00edstica deben mejorar la detecci\u00f3n y la respuesta a las interrupciones y aprovechar las tecnolog\u00edas para manejar las acciones correctivas.<br \/>\u2022 Ante la continua escasez de mano de obra, las empresas deben maximizar sus limitados recursos humanos, pero evitando su explotaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u2022 A medida que el mundo adopta objetivos de sostenibilidad m\u00e1s ambiciosos, los proveedores de log\u00edstica deben minimizar sus impactos ambientales.<\/p>\n<p style=\"text-align: justify;\">\u00bfC\u00f3mo pueden los equipos de log\u00edstica concentrarse en estas prioridades, cuando con demasiada frecuencia tienen dificultades para completar las tareas diarias y entregarlas a tiempo? Con las nuevas tecnolog\u00edas que permiten que los equipos de log\u00edstica operen de forma m\u00e1s r\u00e1pida, inteligente, \u00e1gil y rentable cada d\u00eda. Analicemos cada uno de estos tres puntos\u2026<\/p>\n<p style=\"text-align: justify;\">Identificaci\u00f3n temprana de interrupciones = respuesta unificada m\u00e1s r\u00e1pida<br \/>\u00bfC\u00f3mo pueden las organizaciones de log\u00edstica incorporar sistemas de alerta temprana que les permitan actuar con rapidez e innovaci\u00f3n cuando ocurre algo inesperado? Parte de la respuesta radica en realizar un cambio cultural. Los equipos de log\u00edstica deben eliminar sus silos funcionales y objetivos estrechos, y centrarse en objetivos compartidos, flujos de trabajo fluidos en todas las funciones y excelencia de la cadena de suministro de un extremo a otro.<\/p>\n<p style=\"text-align: justify;\">Los profesionales de la log\u00edstica deben pasar de un enfoque t\u00e1ctico en las actividades dispares de la gesti\u00f3n de pedidos, almacenes y transporte a una perspectiva m\u00e1s estrat\u00e9gica que considere el desempe\u00f1o de la cadena de suministro integral. Esta visi\u00f3n amplia permite que el equipo de log\u00edstica reaccione de forma orquestada y sincronizada a la primera se\u00f1al de interrupci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El Informe sobre el estado de la ejecuci\u00f3n de la cadena de suministro de 2021, realizado por Reuters Events Supply Chain en asociaci\u00f3n con Blue Yonder, revel\u00f3 que el 63% de los fabricantes y minoristas, y el 60% de los proveedores de log\u00edstica, creen que sus esfuerzos para crear visibilidad de extremo a extremo est\u00e1n dando frutos. Sin embargo, un art\u00edculo reciente de Forbes se\u00f1al\u00f3 que, si bien el 92% de los ejecutivos cree que la visibilidad de la cadena de suministro es fundamental, solo el 27% de sus empresas lo han logrado.<\/p>\n<p style=\"text-align: justify;\">La tecnolog\u00eda avanzada, incluida la inteligencia artificial (IA), es fundamental para permitir esta transformaci\u00f3n cultural. Los equipos funcionales no pueden trabajar en conjunto a menos que compartan los mismos datos, la misma vista de un extremo a otro y el mismo objetivo de llevar los productos al cliente de manera rentable y r\u00e1pida.<\/p>\n<p style=\"text-align: justify;\">Trabajar la escasez de mano de obra de forma m\u00e1s inteligente, no m\u00e1s exigente<br \/>Ciertamente, no es ning\u00fan secreto que la industria de la log\u00edstica global, como muchas otras industrias, est\u00e1 cerrando 2021 en medio de una verdadera crisis laboral, con una importante p\u00e9rdida de la fuerza laboral. Adem\u00e1s, los titulares est\u00e1n llenos de predicciones espantosas sobre c\u00f3mo 2022 se caracterizar\u00e1 por la continua escasez de conductores, empleados de almac\u00e9n y otros profesionales cr\u00edticos de la log\u00edstica.<\/p>\n<p style=\"text-align: justify;\">La forma m\u00e1s prometedora de maximizar las contribuciones de la fuerza laboral es aprovechar la tecnolog\u00eda avanzada, incluida la inteligencia artificial, para permitir que los colaboradores trabajen de manera m\u00e1s inteligente, no m\u00e1s dif\u00edcil. Si bien solo el 25% de los encuestados utiliza la rob\u00f3tica de almac\u00e9n, Blue Yonder espera que la tendencia contin\u00fae aumentando. La rob\u00f3tica y la automatizaci\u00f3n de tareas aprovechan al m\u00e1ximo los recursos humanos limitados, al tiempo que liberan a los empleados disponibles para que se concentren en el trabajo estrat\u00e9gico en lugar del trabajo manual. La gesti\u00f3n laboral integrada aborda el compromiso y la retenci\u00f3n de los empleados, la gesti\u00f3n sistem\u00e1tica del desempe\u00f1o y la previsi\u00f3n de los requisitos de la fuerza laboral para facilitar la planificaci\u00f3n a largo plazo.<\/p>\n<p style=\"text-align: justify;\">M\u00e1s que nunca, actuar de forma sostenible tiene un buen sentido comercial<br \/>El Informe del estado de ejecuci\u00f3n de la cadena de suministro de 2021, realizado por Reuters Events Supply Chain en asociaci\u00f3n con Blue Yonder, encontr\u00f3 que el 53% de los fabricantes y minoristas, y el 50% de los proveedores de log\u00edstica, est\u00e1n invirtiendo en programas de sostenibilidad. Y con raz\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En todo el mundo, pr\u00e1cticamente todos los pa\u00edses imponen regulaciones ambientales m\u00e1s estrictas, con el objetivo de minimizar las emisiones de carbono y mitigar los efectos del cambio clim\u00e1tico. El presidente de los Estados Unidos, Joe Biden, anunci\u00f3 recientemente un objetivo de reducir las emisiones de gases de efecto invernadero en el pa\u00eds hasta en un 52% para 2030, en comparaci\u00f3n con los niveles de referencia de 2005.<\/p>\n<p style=\"text-align: justify;\">Debido a que la industria del transporte global es un contribuyente principal de emisiones, eliminar millas y reducir la huella de carbono es la responsabilidad que deben hacer las organizaciones de log\u00edstica.<\/p>\n<p style=\"text-align: justify;\">Centrarse en operaciones m\u00e1s sostenibles no es solo lo correcto, es lo m\u00e1s inteligente y rentable. Basados \u200b\u200ben objetivos de sostenibilidad predefinidos, los motores de optimizaci\u00f3n de IA toman decisiones inteligentes y ambientalmente responsables que sacan a los camiones de la carretera, minimizan el papeleo, reducen el desperdicio y respaldan otras iniciativas ecol\u00f3gicas. Al mismo tiempo, estas decisiones mejoran las m\u00e9tricas financieras y los m\u00e1rgenes de ganancias al optimizar la productividad de los activos f\u00edsicos y reducir los costos de combustible y energ\u00eda de la empresa.<\/p>\n<p style=\"text-align: justify;\">Si los \u00faltimos dos a\u00f1os nos han ense\u00f1ado algo, es que debemos preparar nuestras cadenas de suministro para lo inesperado. Afortunadamente, los equipos de log\u00edstica pueden aplicar soluciones tecnol\u00f3gicas en constante avance para prepararse para un futuro incierto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">Simplemente no se sabe qu\u00e9 traer\u00e1 el nuevo a\u00f1o en t\u00e9rminos de desaf\u00edos log\u00edsticos emergentes. Despu\u00e9s de dos a\u00f1os incre\u00edblemente desafiantes en la industria de la log\u00edstica global, dejemos de lado cualquier expectativa de que el panorama, alguna vez, vuelva a la \u00abnormalidad\u00bb.<\/p>\n","protected":false},"author":1,"featured_media":7077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[83],"tags":[],"class_list":["post-7078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022 - Revista Logistec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022 - Revista Logistec\" \/>\n<meta property=\"og:description\" content=\"Simplemente no se sabe qu\u00e9 traer\u00e1 el nuevo a\u00f1o en t\u00e9rminos de desaf\u00edos log\u00edsticos emergentes. Despu\u00e9s de dos a\u00f1os incre\u00edblemente desafiantes en la industria de la log\u00edstica global, dejemos de lado cualquier expectativa de que el panorama, alguna vez, vuelva a la &quot;normalidad&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Logistec\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-12T11:59:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2021\/11\/Terence-Leung-Photo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\"},\"headline\":\"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022\",\"datePublished\":\"2021-11-12T11:59:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/\"},\"wordCount\":1145,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Terence-Leung-Photo-1.jpg\",\"articleSection\":[\"AN\u00c1LISIS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/\",\"name\":\"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022 - Revista Logistec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Terence-Leung-Photo-1.jpg\",\"datePublished\":\"2021-11-12T11:59:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Terence-Leung-Photo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revistalogistec.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Terence-Leung-Photo-1.jpg\",\"width\":850,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/2021\\\/11\\\/12\\\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.revistalogistec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#website\",\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/\",\"name\":\"Revista Logistec\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revistalogistec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revistalogistec.com\\\/#\\\/schema\\\/person\\\/b25cced65507282f3fc6eb806b1db4f0\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.revistalogistec.com\"],\"url\":\"https:\\\/\\\/www.revistalogistec.com\\\/index.php\\\/author\\\/admin_revlog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022 - Revista Logistec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/","og_locale":"es_ES","og_type":"article","og_title":"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022 - Revista Logistec","og_description":"Simplemente no se sabe qu\u00e9 traer\u00e1 el nuevo a\u00f1o en t\u00e9rminos de desaf\u00edos log\u00edsticos emergentes. Despu\u00e9s de dos a\u00f1os incre\u00edblemente desafiantes en la industria de la log\u00edstica global, dejemos de lado cualquier expectativa de que el panorama, alguna vez, vuelva a la \"normalidad\".","og_url":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/","og_site_name":"Revista Logistec","article_published_time":"2021-11-12T11:59:55+00:00","og_image":[{"width":850,"height":607,"url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2021\/11\/Terence-Leung-Photo-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/#article","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/"},"author":{"name":"admin","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"headline":"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022","datePublished":"2021-11-12T11:59:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/"},"wordCount":1145,"commentCount":0,"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2021\/11\/Terence-Leung-Photo-1.jpg","articleSection":["AN\u00c1LISIS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/","url":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/","name":"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022 - Revista Logistec","isPartOf":{"@id":"https:\/\/www.revistalogistec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2021\/11\/Terence-Leung-Photo-1.jpg","datePublished":"2021-11-12T11:59:55+00:00","author":{"@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0"},"breadcrumb":{"@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/#primaryimage","url":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2021\/11\/Terence-Leung-Photo-1.jpg","contentUrl":"https:\/\/www.revistalogistec.com\/wp-content\/uploads\/2021\/11\/Terence-Leung-Photo-1.jpg","width":850,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.revistalogistec.com\/index.php\/2021\/11\/12\/tres-imperativos-logisticos-para-gestionar-la-incertidumbre-y-las-interrupciones-en-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.revistalogistec.com\/"},{"@type":"ListItem","position":2,"name":"TRES IMPERATIVOS LOG\u00cdSTICOS PARA GESTIONAR LA INCERTIDUMBRE Y LAS INTERRUPCIONES EN 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.revistalogistec.com\/#website","url":"https:\/\/www.revistalogistec.com\/","name":"Revista Logistec","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistalogistec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.revistalogistec.com\/#\/schema\/person\/b25cced65507282f3fc6eb806b1db4f0","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94631f712dee24b50f2f12a7caf62df22b2c346945fcff655ce85b674bebf6fd?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.revistalogistec.com"],"url":"https:\/\/www.revistalogistec.com\/index.php\/author\/admin_revlog\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/7078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/comments?post=7078"}],"version-history":[{"count":0,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/posts\/7078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media\/7077"}],"wp:attachment":[{"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/media?parent=7078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/categories?post=7078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistalogistec.com\/index.php\/wp-json\/wp\/v2\/tags?post=7078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}